{"id":19775,"date":"2026-01-22T06:20:52","date_gmt":"2026-01-22T06:20:52","guid":{"rendered":"https:\/\/www.usviodr.com\/empleo\/"},"modified":"2026-04-11T20:49:42","modified_gmt":"2026-04-11T20:49:42","slug":"empleo","status":"publish","type":"page","link":"https:\/\/www.usviodr.com\/es\/empleo\/","title":{"rendered":"Empleo"},"content":{"rendered":"\n<div class=\"wp-block-cover alignfull\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" class=\"wp-block-cover__image-background wp-image-388 size-full\" alt=\"\" src=\"https:\/\/www.usviodr.com\/wp-content\/uploads\/2026\/01\/DSC00543-scaled-2.jpg\" data-object-fit=\"cover\" srcset=\"https:\/\/www.usviodr.com\/wp-content\/uploads\/2026\/01\/DSC00543-scaled-2.jpg 2560w, https:\/\/www.usviodr.com\/wp-content\/uploads\/2026\/01\/DSC00543-scaled-2-300x200.jpg 300w, https:\/\/www.usviodr.com\/wp-content\/uploads\/2026\/01\/DSC00543-scaled-2-1024x683.jpg 1024w, https:\/\/www.usviodr.com\/wp-content\/uploads\/2026\/01\/DSC00543-scaled-2-768x512.jpg 768w, https:\/\/www.usviodr.com\/wp-content\/uploads\/2026\/01\/DSC00543-scaled-2-1536x1024.jpg 1536w, https:\/\/www.usviodr.com\/wp-content\/uploads\/2026\/01\/DSC00543-scaled-2-2048x1366.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><span aria-hidden=\"true\" class=\"wp-block-cover__background has-base-2-background-color has-background-dim\"><\/span><div class=\"wp-block-cover__inner-container has-global-padding is-layout-constrained wp-container-core-cover-is-layout-ee01b810 wp-block-cover-is-layout-constrained\">\n<h1 class=\"wp-block-heading has-base-color has-text-color has-link-color has-body-font-family wp-elements-c502e249a5f6dda84ac13cec8c4703dd\"><strong>Empleo<\/strong><\/h1>\n\n\n\n<p class=\"has-base-color has-text-color has-link-color wp-elements-aed935c7cb56a87df62358e3204342af\">Browse disaster-related employment opportunities<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\" style=\"padding-top:0\">\n<div class=\"wp-block-button is-style-fill\"><a class=\"wp-block-button__link has-base-2-color has-text-color has-background has-link-color has-body-font-family has-custom-font-size wp-element-button\" href=\"https:\/\/www.usviodr.com\/es\/puestos\/\" style=\"border-top-left-radius:28px;border-top-right-radius:28px;border-bottom-left-radius:28px;border-bottom-right-radius:28px;background-color:#ffb613;font-size:clamp(14px, 0.875rem + ((1vw - 3.2px) * 0.392), 18px);\">Ver todos los puestos vacantes<\/a><\/div>\n<\/div>\n<\/div><\/div>\n\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\" style=\"padding-top:60px;padding-bottom:60px\">\n<h2 class=\"wp-block-heading has-text-align-center has-text-color has-link-color wp-elements-f3e1cef3fa904c2f82cb348da98ed3d5\" style=\"color:#0767a9;padding-top:var(--wp--preset--spacing--10);padding-bottom:30px\"><strong>Estamos reconstruyendo<\/strong><\/h2>\n\n\n\n<div class=\"wp-block-group career-shadow has-base-background-color has-background is-layout-flow wp-block-group-is-layout-flow\" style=\"border-top-left-radius:20px;border-top-right-radius:20px;border-bottom-left-radius:20px;border-bottom-right-radius:20px;padding-top:30px;padding-right:30px;padding-bottom:30px;padding-left:30px\">\n<p class=\"has-text-align-center\">Las agencias gubernamentales de todas las Islas V\u00edrgenes contin\u00faan contratando empleados para cientos de puestos de trabajo. Hay puestos<br\/>disponibles para numerosas disciplinas, incluyendo asistentes administrativos, ingenieros, planificadores y especialistas en conservaci\u00f3n hist\u00f3rica,<br\/>medioambiente y seguros contra inundaciones. \u00a1\u00danase a nuestro equipo hoy mismo!<br\/><\/p>\n\n\n\n<p class=\"has-text-align-center has-text-color has-link-color wp-elements-482eb3858fa8f960554690dd55713a80\" style=\"color:#0767a9;font-style:normal;font-weight:600\"><strong>\u00danase a nosotros<\/strong><\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-a89b3969 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-fill\"><a class=\"wp-block-button__link has-base-2-color has-text-color has-background has-link-color has-body-font-family has-custom-font-size wp-element-button\" href=\"https:\/\/www.usviodr.com\/es\/puestos\/\" style=\"border-top-left-radius:28px;border-top-right-radius:28px;border-bottom-left-radius:28px;border-bottom-right-radius:28px;background-color:#ffb613;padding-top:15px;padding-right:20px;padding-bottom:15px;padding-left:20px;font-size:clamp(14px, 0.875rem + ((1vw - 3.2px) * 0.392), 18px);\">Ver todos los puestos vacantes<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\" style=\"padding-top:0px;padding-bottom:50px\">\n<h2 class=\"wp-block-heading has-text-align-center has-text-color has-link-color wp-elements-9f76da3c96c52c4a98fa4d959aafcba7\" style=\"color:#0767a9;padding-bottom:var(--wp--preset--spacing--50)\"><strong>Puestos destacados<\/strong><\/h2>\n\n\n    <div class=\"jobs-grid\">\n        \n            \n            <div class=\"job-card\">\n                <div class=\"job-icon\">\n                    <img decoding=\"async\" src=\"https:\/\/www.usviodr.com\/wp-content\/themes\/ord-theme\/assets\/images\/Layer-83.png\" alt=\"\" loading=\"lazy\">\n                <\/div>\n\n                <h4 class=\"job-title\">Student Intern &#8211; Kahua Data Migration<\/h4>\n\n                <div class=\"job-meta\">\n                    <p class=\"agency\">Office of Disaster Recovery<\/p><p class=\"district\">Territorial<\/p>                <\/div>\n\n                <div class=\"job-actions\">\n                    <a href=\"https:\/\/www.usviodr.com\/es\/jobs\/student-intern-kahua-data-migration\/?job_title=Student%20Intern%20%26%238211%3B%20Kahua%20Data%20Migration\" class=\"job-btn apply-btn\" rel=\"noopener\">\n                        Solicitar                    <\/a>\n                                        <a href=\"https:\/\/www.usviodr.com\/es\/jobs\/student-intern-kahua-data-migration\/\" class=\"job-btn closing-btn\" rel=\"noopener\">\n                        <span class=\"default-text\">Fecha de cierre<\/span>\n                        <span class=\"hover-text\">05 \/08 \/2026<\/span>\n                    <\/a>\n                <\/div>\n            <\/div>\n\n        \n            \n            <div class=\"job-card\">\n                <div class=\"job-icon\">\n                    <img decoding=\"async\" src=\"https:\/\/www.usviodr.com\/wp-content\/themes\/ord-theme\/assets\/images\/Layer-84.png\" alt=\"\" loading=\"lazy\">\n                <\/div>\n\n                <h4 class=\"job-title\">Student Intern &#8211; Financial Analyst<\/h4>\n\n                <div class=\"job-meta\">\n                    <p class=\"agency\">Office of Disaster Recovery<\/p><p class=\"district\">Territorial<\/p>                <\/div>\n\n                <div class=\"job-actions\">\n                    <a href=\"https:\/\/www.usviodr.com\/es\/jobs\/student-intern-financial-analyst\/?job_title=Student%20Intern%20%26%238211%3B%20Financial%20Analyst\" class=\"job-btn apply-btn\" rel=\"noopener\">\n                        Solicitar                    <\/a>\n                                        <a href=\"https:\/\/www.usviodr.com\/es\/jobs\/student-intern-financial-analyst\/\" class=\"job-btn closing-btn\" rel=\"noopener\">\n                        <span class=\"default-text\">Fecha de cierre<\/span>\n                        <span class=\"hover-text\">05 \/08 \/2026<\/span>\n                    <\/a>\n                <\/div>\n            <\/div>\n\n        \n            \n            <div class=\"job-card\">\n                <div class=\"job-icon\">\n                    <img decoding=\"async\" src=\"https:\/\/www.usviodr.com\/wp-content\/themes\/ord-theme\/assets\/images\/Layer-85.png\" alt=\"\" loading=\"lazy\">\n                <\/div>\n\n                <h4 class=\"job-title\">Executive Assistant<\/h4>\n\n                <div class=\"job-meta\">\n                    <p class=\"agency\">Office of Disaster Recovery<\/p><p class=\"district\">St. Croix<\/p>                <\/div>\n\n                <div class=\"job-actions\">\n                    <a href=\"https:\/\/www.usviodr.com\/es\/jobs\/executive-assistant\/?job_title=Executive%20Assistant\" class=\"job-btn apply-btn\" rel=\"noopener\">\n                        Solicitar                    <\/a>\n                                        <a href=\"https:\/\/www.usviodr.com\/es\/jobs\/executive-assistant\/\" class=\"job-btn closing-btn\" rel=\"noopener\">\n                        <span class=\"default-text\">Fecha de cierre<\/span>\n                        <span class=\"hover-text\">04 \/24 \/2026<\/span>\n                    <\/a>\n                <\/div>\n            <\/div>\n\n            <\/div>\n    \n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Estamos reconstruyendo Las agencias gubernamentales de todas las Islas V\u00edrgenes contin\u00faan contratando empleados para cientos de puestos de trabajo. Hay puestosdisponibles para numerosas disciplinas, incluyendo asistentes administrativos, ingenieros, planificadores y especialistas en conservaci\u00f3n hist\u00f3rica,medioambiente y seguros contra inundaciones. \u00a1\u00danase a nuestro equipo hoy mismo! \u00danase a nosotros Puestos destacados<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"project_id":"","notification":"","due_date":"","status":"","show_rebuild":"","footnotes":""},"class_list":["post-19775","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Empleo - US VI ODR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.usviodr.com\/es\/empleo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Empleo - US VI ODR\" \/>\n<meta property=\"og:description\" content=\"Estamos reconstruyendo Las agencias gubernamentales de todas las Islas V\u00edrgenes contin\u00faan contratando empleados para cientos de puestos de trabajo. Hay puestosdisponibles para numerosas disciplinas, incluyendo asistentes administrativos, ingenieros, planificadores y especialistas en conservaci\u00f3n hist\u00f3rica,medioambiente y seguros contra inundaciones. \u00a1\u00danase a nuestro equipo hoy mismo! \u00danase a nosotros Puestos destacados\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.usviodr.com\/es\/empleo\/\" \/>\n<meta property=\"og:site_name\" content=\"US VI ODR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/odrusvi\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-11T20:49:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.usviodr.com\/wp-content\/uploads\/2026\/01\/DSC00543-scaled-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@USVIODR\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.usviodr.com\\\/es\\\/empleo\\\/\",\"url\":\"https:\\\/\\\/www.usviodr.com\\\/es\\\/empleo\\\/\",\"name\":\"Empleo - US VI ODR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.usviodr.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.usviodr.com\\\/es\\\/empleo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.usviodr.com\\\/es\\\/empleo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.usviodr.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/DSC00543-scaled-2.jpg\",\"datePublished\":\"2026-01-22T06:20:52+00:00\",\"dateModified\":\"2026-04-11T20:49:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.usviodr.com\\\/es\\\/empleo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.usviodr.com\\\/es\\\/empleo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.usviodr.com\\\/es\\\/empleo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.usviodr.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/DSC00543-scaled-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.usviodr.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/DSC00543-scaled-2.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.usviodr.com\\\/es\\\/empleo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.usviodr.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Empleo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.usviodr.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.usviodr.com\\\/es\\\/\",\"name\":\"US VI ODR\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.usviodr.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.usviodr.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.usviodr.com\\\/es\\\/#organization\",\"name\":\"US VI ODR\",\"url\":\"https:\\\/\\\/www.usviodr.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.usviodr.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.usviodr.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/ODR-LOGO.png\",\"contentUrl\":\"https:\\\/\\\/www.usviodr.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/ODR-LOGO.png\",\"width\":105,\"height\":105,\"caption\":\"US VI ODR\"},\"image\":{\"@id\":\"https:\\\/\\\/www.usviodr.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/odrusvi\",\"https:\\\/\\\/x.com\\\/USVIODR\",\"https:\\\/\\\/www.instagram.com\\\/usviofficeofdisasterrecovery\\\/?hl=en\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Empleo - US VI ODR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.usviodr.com\/es\/empleo\/","og_locale":"es_ES","og_type":"article","og_title":"Empleo - US VI ODR","og_description":"Estamos reconstruyendo Las agencias gubernamentales de todas las Islas V\u00edrgenes contin\u00faan contratando empleados para cientos de puestos de trabajo. Hay puestosdisponibles para numerosas disciplinas, incluyendo asistentes administrativos, ingenieros, planificadores y especialistas en conservaci\u00f3n hist\u00f3rica,medioambiente y seguros contra inundaciones. \u00a1\u00danase a nuestro equipo hoy mismo! \u00danase a nosotros Puestos destacados","og_url":"https:\/\/www.usviodr.com\/es\/empleo\/","og_site_name":"US VI ODR","article_publisher":"https:\/\/www.facebook.com\/odrusvi","article_modified_time":"2026-04-11T20:49:42+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/www.usviodr.com\/wp-content\/uploads\/2026\/01\/DSC00543-scaled-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@USVIODR","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.usviodr.com\/es\/empleo\/","url":"https:\/\/www.usviodr.com\/es\/empleo\/","name":"Empleo - US VI ODR","isPartOf":{"@id":"https:\/\/www.usviodr.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.usviodr.com\/es\/empleo\/#primaryimage"},"image":{"@id":"https:\/\/www.usviodr.com\/es\/empleo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.usviodr.com\/wp-content\/uploads\/2026\/01\/DSC00543-scaled-2.jpg","datePublished":"2026-01-22T06:20:52+00:00","dateModified":"2026-04-11T20:49:42+00:00","breadcrumb":{"@id":"https:\/\/www.usviodr.com\/es\/empleo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.usviodr.com\/es\/empleo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.usviodr.com\/es\/empleo\/#primaryimage","url":"https:\/\/www.usviodr.com\/wp-content\/uploads\/2026\/01\/DSC00543-scaled-2.jpg","contentUrl":"https:\/\/www.usviodr.com\/wp-content\/uploads\/2026\/01\/DSC00543-scaled-2.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.usviodr.com\/es\/empleo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.usviodr.com\/es\/"},{"@type":"ListItem","position":2,"name":"Empleo"}]},{"@type":"WebSite","@id":"https:\/\/www.usviodr.com\/es\/#website","url":"https:\/\/www.usviodr.com\/es\/","name":"US VI ODR","description":"","publisher":{"@id":"https:\/\/www.usviodr.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.usviodr.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.usviodr.com\/es\/#organization","name":"US VI ODR","url":"https:\/\/www.usviodr.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.usviodr.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.usviodr.com\/wp-content\/uploads\/2026\/01\/ODR-LOGO.png","contentUrl":"https:\/\/www.usviodr.com\/wp-content\/uploads\/2026\/01\/ODR-LOGO.png","width":105,"height":105,"caption":"US VI ODR"},"image":{"@id":"https:\/\/www.usviodr.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/odrusvi","https:\/\/x.com\/USVIODR","https:\/\/www.instagram.com\/usviofficeofdisasterrecovery\/?hl=en"]}]}},"_links":{"self":[{"href":"https:\/\/www.usviodr.com\/es\/wp-json\/wp\/v2\/pages\/19775","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.usviodr.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.usviodr.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.usviodr.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.usviodr.com\/es\/wp-json\/wp\/v2\/comments?post=19775"}],"version-history":[{"count":1,"href":"https:\/\/www.usviodr.com\/es\/wp-json\/wp\/v2\/pages\/19775\/revisions"}],"predecessor-version":[{"id":19777,"href":"https:\/\/www.usviodr.com\/es\/wp-json\/wp\/v2\/pages\/19775\/revisions\/19777"}],"wp:attachment":[{"href":"https:\/\/www.usviodr.com\/es\/wp-json\/wp\/v2\/media?parent=19775"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}